{"id":24029,"date":"2026-05-12T09:53:52","date_gmt":"2026-05-12T13:53:52","guid":{"rendered":"https:\/\/visitavina.munivina.cl\/?post_type=mec-events&#038;p=24029"},"modified":"2026-05-12T09:58:37","modified_gmt":"2026-05-12T13:58:37","slug":"stand-up-the-faba-show","status":"publish","type":"mec-events","link":"https:\/\/visitavina.munivina.cl\/br\/actividad\/stand-up-the-faba-show\/","title":{"rendered":"Stand up | The Faba show"},"content":{"rendered":"<p><span data-sheets-root=\"1\">Faba aterriza en Chile porque ya pas\u00f3 los cuarenta y ya sabemos lo que significa; esta soltera y feliz\u2026 Pero solo por momentos, breves momentos, casi instantes, piensa que podr\u00eda tener una pareja para los domingos de baj\u00f3n, para bailar en una boda o para contarle como le fue en su d\u00eda. En estos momentos de debilidad es donde se convierte en una mujer muy proactiva y hace un show de comedia con el \u00fanico fin de encontrar un novio. Si es un sugar o un col\u00e1geno no importar\u00e1, ella solo quiere enamorarse.<\/span><\/p>\n<p><span data-sheets-root=\"1\">M\u00e1s informaci\u00f3n en Instagram | <a class=\"in-cell-link\" href=\"https:\/\/www.instagram.com\/barbonescomedy\/\" target=\"_blank\" rel=\"noopener nofollow\">@barbonescomedy<\/a><\/span><br \/>\n<span data-sheets-root=\"1\">Venta de entradas | <a class=\"in-cell-link\" href=\"https:\/\/comediaticket.cl\/details\/events_details\/cuarentona-del-amor-en-chile-vina-del-mar_1wg3c\" target=\"_blank\" rel=\"noopener nofollow\">COMEDIATICKET<\/a><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Faba aterriza en Chile porque ya pas\u00f3 los cuarenta y ya sabemos lo que significa; esta soltera y feliz\u2026 Pero solo por momentos, breves momentos, casi instantes, piensa que podr\u00eda tener una pareja para los domingos de baj\u00f3n, para bailar en una boda o para contarle como le fue en su d\u00eda. En estos momentos [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[],"class_list":["post-24029","mec-events","type-mec-events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/visitavina.munivina.cl\/br\/wp-json\/wp\/v2\/mec-events\/24029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitavina.munivina.cl\/br\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/visitavina.munivina.cl\/br\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/visitavina.munivina.cl\/br\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/visitavina.munivina.cl\/br\/wp-json\/wp\/v2\/comments?post=24029"}],"wp:attachment":[{"href":"https:\/\/visitavina.munivina.cl\/br\/wp-json\/wp\/v2\/media?parent=24029"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitavina.munivina.cl\/br\/wp-json\/wp\/v2\/tags?post=24029"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/visitavina.munivina.cl\/br\/wp-json\/wp\/v2\/mec_category?post=24029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}