{"id":24695,"date":"2026-09-01T11:40:00","date_gmt":"2026-09-01T15:40:00","guid":{"rendered":"https:\/\/visitavina.munivina.cl\/?post_type=mec-events&#038;p=24695"},"modified":"2026-09-01T11:40:00","modified_gmt":"2026-09-01T15:40:00","slug":"ciclo-formacion-de-publico-ficvina-2","status":"publish","type":"mec-events","link":"https:\/\/visitavina.munivina.cl\/en\/actividad\/ciclo-formacion-de-publico-ficvina-2\/","title":{"rendered":"Ciclo Formaci\u00f3n de P\u00fablico FICVI\u00d1A"},"content":{"rendered":"<p><span data-sheets-root=\"1\">\u201cLa Patagonia Rebelde\u201d | (1974) |Dir. H\u00e9ctor Olivera (Argentina)<br \/>\nEn 1920, unos obreros de la Patagonia Argentina, agrupados en sociedades anarquistas y socialistas, deciden hacer una huelga exigiendo mejoras laborales. Entre los trabajadores hay numerosos emigrantes europeos que influyen ideol\u00f3gicamente en sus compa\u00f1eros. La situaci\u00f3n se hace insostenible y el gobierno de Yrigoyen manda, desde Buenos Aires, al teniente coronel Zavala para que restablezca el orden.<\/span><\/p>\n<p><span data-sheets-root=\"1\">M\u00e1s informaci\u00f3n en Instagram | <a class=\"in-cell-link\" href=\"https:\/\/www.instagram.com\/museopalaciorioja\/\" target=\"_blank\" rel=\"noopener nofollow\">@museopalaciorioja<\/a><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>\u201cLa Patagonia Rebelde\u201d | (1974) |Dir. H\u00e9ctor Olivera (Argentina) En 1920, unos obreros de la Patagonia Argentina, agrupados en sociedades anarquistas y socialistas, deciden hacer una huelga exigiendo mejoras laborales. Entre los trabajadores hay numerosos emigrantes europeos que influyen ideol\u00f3gicamente en sus compa\u00f1eros. La situaci\u00f3n se hace insostenible y el gobierno de Yrigoyen manda, desde [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[],"class_list":["post-24695","mec-events","type-mec-events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/visitavina.munivina.cl\/en\/wp-json\/wp\/v2\/mec-events\/24695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitavina.munivina.cl\/en\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/visitavina.munivina.cl\/en\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/visitavina.munivina.cl\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/visitavina.munivina.cl\/en\/wp-json\/wp\/v2\/comments?post=24695"}],"wp:attachment":[{"href":"https:\/\/visitavina.munivina.cl\/en\/wp-json\/wp\/v2\/media?parent=24695"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitavina.munivina.cl\/en\/wp-json\/wp\/v2\/tags?post=24695"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/visitavina.munivina.cl\/en\/wp-json\/wp\/v2\/mec_category?post=24695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}